{"id":557,"date":"2020-03-18T18:06:05","date_gmt":"2020-03-18T21:06:05","guid":{"rendered":"https:\/\/www.emporiofazbem.com\/blog\/?p=557"},"modified":"2020-03-18T18:06:05","modified_gmt":"2020-03-18T21:06:05","slug":"produtos-que-aumentam-imunidade","status":"publish","type":"post","link":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/","title":{"rendered":"Produtos que aumentam a imunidade"},"content":{"rendered":"<p>-Ch\u00e1 branco e ch\u00e1 verde: ricos em catequina, poderoso antioxidante. A subst\u00e2ncia ainda fortalece o sistema imunol\u00f3gico. <\/p>\n<p>-Chlorela: tem atividade antitumoral, antibacteriana e antiviral, al\u00e9m de fortalecer as c\u00e9lulas e combater alergias.<\/p>\n<p>-Cogumelo agaricus: cont\u00e9m lentinana, subst\u00e2ncia que aumenta a produ\u00e7\u00e3o das c\u00e9lulas de defesa do organismo.<\/p>\n<p>-Geleia real: estimula o sistema imunol\u00f3gico, combatendo infec\u00e7\u00f5es por v\u00edrus e bact\u00e9rias. <\/p>\n<p>-Gengibre: \u00e9 expectorante, reduz a inflama\u00e7\u00e3o e a dor. <\/p>\n<p>-Glutamina: suas principais fun\u00e7\u00f5es est\u00e3o relacionadas com as rea\u00e7\u00f5es de produ\u00e7\u00e3o de energia, atua como combust\u00edvel para o sistema imune e para os enter\u00f3citos (c\u00e9lulas do intestino).<\/p>\n<p>-Mel: cont\u00e9m subst\u00e2ncias que agem como antibi\u00f3ticos naturais. Eficaz contra os sintomas de gripes e resfriados. Pode ser coadjuvante no tratamento de problemas pulmonares e da garganta. <\/p>\n<p>-\u00d3leo de alho: fonte de alicina, estimula a resposta imunol\u00f3gica. <\/p>\n<p>-\u00d3leo de coco: rico em \u00e1cido l\u00e1urico e capr\u00edlico, possui atividade antiviral e antibacteriana.<\/p>\n<p>-P\u00f3len: rico em prote\u00ednas, vitaminas e minerais que ajudam na forma\u00e7\u00e3o de anticorpos, fortalecendo o organismo. <\/p>\n<p>-Pr\u00f3polis: \u00e9 rico em flavonoides e antioxidantes, possui a\u00e7\u00e3o antibacteriana, combate resfriados e gripes e age contra fungos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Ch\u00e1 branco e ch\u00e1 verde: ricos em catequina, poderoso antioxidante. A subst\u00e2ncia ainda fortalece o sistema imunol\u00f3gico. -Chlorela: tem atividade antitumoral, antibacteriana e antiviral, al\u00e9m de fortalecer as c\u00e9lulas e combater alergias. -Cogumelo agaricus: cont\u00e9m lentinana, subst\u00e2ncia que aumenta a produ\u00e7\u00e3o das c\u00e9lulas de defesa do organismo. -Geleia real: estimula&#8230;<\/p>\n","protected":false},"author":1,"featured_media":558,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Produtos que aumentam a imunidade - Emp\u00f3rio Faz Bem<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Produtos que aumentam a imunidade - Emp\u00f3rio Faz Bem\" \/>\n<meta property=\"og:description\" content=\"-Ch\u00e1 branco e ch\u00e1 verde: ricos em catequina, poderoso antioxidante. A subst\u00e2ncia ainda fortalece o sistema imunol\u00f3gico. -Chlorela: tem atividade antitumoral, antibacteriana e antiviral, al\u00e9m de fortalecer as c\u00e9lulas e combater alergias. -Cogumelo agaricus: cont\u00e9m lentinana, subst\u00e2ncia que aumenta a produ\u00e7\u00e3o das c\u00e9lulas de defesa do organismo. -Geleia real: estimula...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Emp\u00f3rio Faz Bem\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/emporio.fazbem\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-18T21:06:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2020\/03\/imunidadea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"O Emp\u00f3rio FazBem\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"O Emp\u00f3rio FazBem\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/\"},\"author\":{\"name\":\"O Emp\u00f3rio FazBem\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#\\\/schema\\\/person\\\/4256177c5ac5a4a9d8553ae440f1c9a2\"},\"headline\":\"Produtos que aumentam a imunidade\",\"datePublished\":\"2020-03-18T21:06:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/\"},\"wordCount\":216,\"publisher\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/imunidadea.jpg\",\"articleSection\":[\"Dicas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/\",\"name\":\"Produtos que aumentam a imunidade - Emp\u00f3rio Faz Bem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/imunidadea.jpg\",\"datePublished\":\"2020-03-18T21:06:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/imunidadea.jpg\",\"contentUrl\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/imunidadea.jpg\",\"width\":1700,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/produtos-que-aumentam-imunidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos que aumentam a imunidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/\",\"name\":\"Emp\u00f3rio Faz Bem\",\"description\":\"Produtos naturais e saud\u00e1veis\",\"publisher\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#organization\",\"name\":\"Emp\u00f3rio Faz Bem\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/trans.png\",\"contentUrl\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/trans.png\",\"width\":249,\"height\":144,\"caption\":\"Emp\u00f3rio Faz Bem\"},\"image\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#\\\/schema\\\/person\\\/4256177c5ac5a4a9d8553ae440f1c9a2\",\"name\":\"O Emp\u00f3rio FazBem\",\"sameAs\":[\"https:\\\/\\\/www.emporiofazbem.com\",\"https:\\\/\\\/www.facebook.com\\\/emporio.fazbem\\\/\"],\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/author\\\/EmporioFazBem\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Produtos que aumentam a imunidade - Emp\u00f3rio Faz Bem","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Produtos que aumentam a imunidade - Emp\u00f3rio Faz Bem","og_description":"-Ch\u00e1 branco e ch\u00e1 verde: ricos em catequina, poderoso antioxidante. A subst\u00e2ncia ainda fortalece o sistema imunol\u00f3gico. -Chlorela: tem atividade antitumoral, antibacteriana e antiviral, al\u00e9m de fortalecer as c\u00e9lulas e combater alergias. -Cogumelo agaricus: cont\u00e9m lentinana, subst\u00e2ncia que aumenta a produ\u00e7\u00e3o das c\u00e9lulas de defesa do organismo. -Geleia real: estimula...","og_url":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/","og_site_name":"Emp\u00f3rio Faz Bem","article_author":"https:\/\/www.facebook.com\/emporio.fazbem\/","article_published_time":"2020-03-18T21:06:05+00:00","og_image":[{"width":1700,"height":850,"url":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2020\/03\/imunidadea.jpg","type":"image\/jpeg"}],"author":"O Emp\u00f3rio FazBem","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"O Emp\u00f3rio FazBem","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/#article","isPartOf":{"@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/"},"author":{"name":"O Emp\u00f3rio FazBem","@id":"https:\/\/emporiofazbem.com\/blog\/#\/schema\/person\/4256177c5ac5a4a9d8553ae440f1c9a2"},"headline":"Produtos que aumentam a imunidade","datePublished":"2020-03-18T21:06:05+00:00","mainEntityOfPage":{"@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/"},"wordCount":216,"publisher":{"@id":"https:\/\/emporiofazbem.com\/blog\/#organization"},"image":{"@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/#primaryimage"},"thumbnailUrl":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2020\/03\/imunidadea.jpg","articleSection":["Dicas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/","url":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/","name":"Produtos que aumentam a imunidade - Emp\u00f3rio Faz Bem","isPartOf":{"@id":"https:\/\/emporiofazbem.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/#primaryimage"},"image":{"@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/#primaryimage"},"thumbnailUrl":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2020\/03\/imunidadea.jpg","datePublished":"2020-03-18T21:06:05+00:00","breadcrumb":{"@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/#primaryimage","url":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2020\/03\/imunidadea.jpg","contentUrl":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2020\/03\/imunidadea.jpg","width":1700,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/emporiofazbem.com\/blog\/produtos-que-aumentam-imunidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/emporiofazbem.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Produtos que aumentam a imunidade"}]},{"@type":"WebSite","@id":"https:\/\/emporiofazbem.com\/blog\/#website","url":"https:\/\/emporiofazbem.com\/blog\/","name":"Emp\u00f3rio Faz Bem","description":"Produtos naturais e saud\u00e1veis","publisher":{"@id":"https:\/\/emporiofazbem.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emporiofazbem.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/emporiofazbem.com\/blog\/#organization","name":"Emp\u00f3rio Faz Bem","url":"https:\/\/emporiofazbem.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/emporiofazbem.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2016\/09\/trans.png","contentUrl":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2016\/09\/trans.png","width":249,"height":144,"caption":"Emp\u00f3rio Faz Bem"},"image":{"@id":"https:\/\/emporiofazbem.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/emporiofazbem.com\/blog\/#\/schema\/person\/4256177c5ac5a4a9d8553ae440f1c9a2","name":"O Emp\u00f3rio FazBem","sameAs":["https:\/\/www.emporiofazbem.com","https:\/\/www.facebook.com\/emporio.fazbem\/"],"url":"https:\/\/emporiofazbem.com\/blog\/author\/EmporioFazBem\/"}]}},"_links":{"self":[{"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/posts\/557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/comments?post=557"}],"version-history":[{"count":1,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/posts\/557\/revisions"}],"predecessor-version":[{"id":559,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/posts\/557\/revisions\/559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/media\/558"}],"wp:attachment":[{"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/categories?post=557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/tags?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}