{"id":667,"date":"2021-06-17T10:46:55","date_gmt":"2021-06-17T13:46:55","guid":{"rendered":"https:\/\/www.emporiofazbem.com\/blog\/?p=667"},"modified":"2021-06-17T10:46:55","modified_gmt":"2021-06-17T13:46:55","slug":"cha-um-pouco-de-conhecimento-deste-universo-parte-i","status":"publish","type":"post","link":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/","title":{"rendered":"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I"},"content":{"rendered":"<p>Bebida mais consumida no mundo, o ch\u00e1 \u00e9, hoje, universal. Da cidade ou do campo, rico ou pobre, s\u00f3 ou acompanhado, nos quatro cantos do mundo, o homem toma ch\u00e1, ainda que, nos diferentes pa\u00edses, cada um o fa\u00e7a \u00e0 sua maneira. Ocidente e Oriente se conhecem, enfim, ao redor de um ch\u00e1.<br \/>\nA China \u00e9 incontestavelmente o \u201cber\u00e7o\u201d do ch\u00e1!<\/p>\n<p>Hoje, como ontem, continua sendo o \u00fanico pa\u00eds do mundo que produz e fabrica todas as \u201ccores\u201d de ch\u00e1s que, calcula-se, giram em torno de 10 mil. Uma vida inteira n\u00e3o seria suficiente para descobrir todos os tipos de ch\u00e1s!<br \/>\nO chazeiro chin\u00eas, cujo nome cient\u00edfico \u00e9 Camellia sinensis, foi descoberto na China h\u00e1 mil\u00eanios.<br \/>\nConta a lenda que, certa vez, o imperador Shen Nong, o Divino Agricultor, resolveu percorrer toda a China para repertoriar todas as esp\u00e9cies de plantas medicinais ali existentes. Um dia, ap\u00f3s longa caminhada pelos campos, Shen Nong adormeceu sob uma \u00e1rvore. Antes, por\u00e9m, sempre atento a sua sa\u00fade, teve o cuidado de colocar a \u00e1gua para ferver antes de beb\u00ea-la. Uma leve aragem soprou e algumas folhas da \u00e1rvore ca\u00edram na \u00e1gua fervente do caldeir\u00e3o. Ao acordar, o imperador encontrou em sua \u00e1gua as folhinhas em infus\u00e3o. Experimentou a \u00e1gua e apreciou-a muit\u00edssimo: adormecera sob um chazeiro&#8230;<\/p>\n<p>No entanto, \u00e9 preciso aguardar a dinastia Tang (618-907) para ver o aparecimento da palavra cha (\u201cch\u00e1\u201d). At\u00e9 ent\u00e3o, eram empregados os termos tu (\u201cplanta amarga\u201d) e depois mieng (\u201cbroto\u201d). De fato, muito rapidamente os chineses perceberam que o melhor do chazeiro eram o broto e as duas primeiras folhas mais novas.<\/p>\n<p>A partir do s\u00e9culo XIX, a cultura do ch\u00e1 organizou-se fora da China.<\/p>\n<p>De 21 a 27 de junho acontecer\u00e1 nas lojas Emp\u00f3rio FazBem o Festival do Ch\u00e1, com degusta\u00e7\u00f5es, conte\u00fados e muita novidade do universo do ch\u00e1. Voc\u00ea \u00e9 nosso(a) convidado(a)!<\/p>\n<p>Fonte: Livro Ch\u00e1: rituais e benef\u00edcios. Autora Christine Dattner. Editora Senac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bebida mais consumida no mundo, o ch\u00e1 \u00e9, hoje, universal. Da cidade ou do campo, rico ou pobre, s\u00f3 ou acompanhado, nos quatro cantos do mundo, o homem toma ch\u00e1, ainda que, nos diferentes pa\u00edses, cada um o fa\u00e7a \u00e0 sua maneira. Ocidente e Oriente se conhecem, enfim, ao redor&#8230;<\/p>\n","protected":false},"author":1,"featured_media":668,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I - Emp\u00f3rio Faz Bem<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I - Emp\u00f3rio Faz Bem\" \/>\n<meta property=\"og:description\" content=\"Bebida mais consumida no mundo, o ch\u00e1 \u00e9, hoje, universal. Da cidade ou do campo, rico ou pobre, s\u00f3 ou acompanhado, nos quatro cantos do mundo, o homem toma ch\u00e1, ainda que, nos diferentes pa\u00edses, cada um o fa\u00e7a \u00e0 sua maneira. Ocidente e Oriente se conhecem, enfim, ao redor...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/\" \/>\n<meta property=\"og:site_name\" content=\"Emp\u00f3rio Faz Bem\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/emporio.fazbem\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T13:46:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2021\/06\/ch\u00e1-parte-I.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"797\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"O Emp\u00f3rio FazBem\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"O Emp\u00f3rio FazBem\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/\"},\"author\":{\"name\":\"O Emp\u00f3rio FazBem\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#\\\/schema\\\/person\\\/4256177c5ac5a4a9d8553ae440f1c9a2\"},\"headline\":\"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I\",\"datePublished\":\"2021-06-17T13:46:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/\"},\"wordCount\":345,\"publisher\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/ch\u00e1-parte-I.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/\",\"name\":\"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I - Emp\u00f3rio Faz Bem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/ch\u00e1-parte-I.png\",\"datePublished\":\"2021-06-17T13:46:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/ch\u00e1-parte-I.png\",\"contentUrl\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/ch\u00e1-parte-I.png\",\"width\":750,\"height\":797},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/\",\"name\":\"Emp\u00f3rio Faz Bem\",\"description\":\"Produtos naturais e saud\u00e1veis\",\"publisher\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#organization\",\"name\":\"Emp\u00f3rio Faz Bem\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/trans.png\",\"contentUrl\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/trans.png\",\"width\":249,\"height\":144,\"caption\":\"Emp\u00f3rio Faz Bem\"},\"image\":{\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/#\\\/schema\\\/person\\\/4256177c5ac5a4a9d8553ae440f1c9a2\",\"name\":\"O Emp\u00f3rio FazBem\",\"sameAs\":[\"https:\\\/\\\/www.emporiofazbem.com\",\"https:\\\/\\\/www.facebook.com\\\/emporio.fazbem\\\/\"],\"url\":\"https:\\\/\\\/emporiofazbem.com\\\/blog\\\/author\\\/EmporioFazBem\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I - Emp\u00f3rio Faz Bem","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I - Emp\u00f3rio Faz Bem","og_description":"Bebida mais consumida no mundo, o ch\u00e1 \u00e9, hoje, universal. Da cidade ou do campo, rico ou pobre, s\u00f3 ou acompanhado, nos quatro cantos do mundo, o homem toma ch\u00e1, ainda que, nos diferentes pa\u00edses, cada um o fa\u00e7a \u00e0 sua maneira. Ocidente e Oriente se conhecem, enfim, ao redor...","og_url":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/","og_site_name":"Emp\u00f3rio Faz Bem","article_author":"https:\/\/www.facebook.com\/emporio.fazbem\/","article_published_time":"2021-06-17T13:46:55+00:00","og_image":[{"width":750,"height":797,"url":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2021\/06\/ch\u00e1-parte-I.png","type":"image\/png"}],"author":"O Emp\u00f3rio FazBem","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"O Emp\u00f3rio FazBem","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/#article","isPartOf":{"@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/"},"author":{"name":"O Emp\u00f3rio FazBem","@id":"https:\/\/emporiofazbem.com\/blog\/#\/schema\/person\/4256177c5ac5a4a9d8553ae440f1c9a2"},"headline":"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I","datePublished":"2021-06-17T13:46:55+00:00","mainEntityOfPage":{"@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/"},"wordCount":345,"publisher":{"@id":"https:\/\/emporiofazbem.com\/blog\/#organization"},"image":{"@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/#primaryimage"},"thumbnailUrl":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2021\/06\/ch\u00e1-parte-I.png","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/","url":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/","name":"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I - Emp\u00f3rio Faz Bem","isPartOf":{"@id":"https:\/\/emporiofazbem.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/#primaryimage"},"image":{"@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/#primaryimage"},"thumbnailUrl":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2021\/06\/ch\u00e1-parte-I.png","datePublished":"2021-06-17T13:46:55+00:00","breadcrumb":{"@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/#primaryimage","url":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2021\/06\/ch\u00e1-parte-I.png","contentUrl":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2021\/06\/ch\u00e1-parte-I.png","width":750,"height":797},{"@type":"BreadcrumbList","@id":"https:\/\/emporiofazbem.com\/blog\/cha-um-pouco-de-conhecimento-deste-universo-parte-i\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/emporiofazbem.com\/blog\/"},{"@type":"ListItem","position":2,"name":"CH\u00c1: Um Pouco de Conhecimento deste Universo \u2013 PARTE I"}]},{"@type":"WebSite","@id":"https:\/\/emporiofazbem.com\/blog\/#website","url":"https:\/\/emporiofazbem.com\/blog\/","name":"Emp\u00f3rio Faz Bem","description":"Produtos naturais e saud\u00e1veis","publisher":{"@id":"https:\/\/emporiofazbem.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emporiofazbem.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/emporiofazbem.com\/blog\/#organization","name":"Emp\u00f3rio Faz Bem","url":"https:\/\/emporiofazbem.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/emporiofazbem.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2016\/09\/trans.png","contentUrl":"https:\/\/emporiofazbem.com\/blog\/wp-content\/uploads\/2016\/09\/trans.png","width":249,"height":144,"caption":"Emp\u00f3rio Faz Bem"},"image":{"@id":"https:\/\/emporiofazbem.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/emporiofazbem.com\/blog\/#\/schema\/person\/4256177c5ac5a4a9d8553ae440f1c9a2","name":"O Emp\u00f3rio FazBem","sameAs":["https:\/\/www.emporiofazbem.com","https:\/\/www.facebook.com\/emporio.fazbem\/"],"url":"https:\/\/emporiofazbem.com\/blog\/author\/EmporioFazBem\/"}]}},"_links":{"self":[{"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/posts\/667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/comments?post=667"}],"version-history":[{"count":1,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/posts\/667\/revisions"}],"predecessor-version":[{"id":669,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/posts\/667\/revisions\/669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/media\/668"}],"wp:attachment":[{"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/media?parent=667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/categories?post=667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emporiofazbem.com\/blog\/wp-json\/wp\/v2\/tags?post=667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}